{"id":1279,"date":"2021-05-05T16:27:33","date_gmt":"2021-05-05T19:27:33","guid":{"rendered":"https:\/\/lacontracara.com\/?p=1279"},"modified":"2021-05-05T16:27:34","modified_gmt":"2021-05-05T19:27:34","slug":"blue-origin-subastara-el-primer-pasaje-para-turismo-espacial","status":"publish","type":"post","link":"https:\/\/lacontracara.com\/index.php\/2021\/05\/05\/blue-origin-subastara-el-primer-pasaje-para-turismo-espacial\/","title":{"rendered":"Blue Origin subastar\u00e1 el primer pasaje para turismo espacial"},"content":{"rendered":"\n<p><strong>Blue Origin<\/strong>, la empresa de cohetes del multimillonario Jeff Bezos,&nbsp;<strong>abrir\u00e1 este mi\u00e9rcoles la venta de billetes para viajes tur\u00edsticos en su nave espacial New Shepard<\/strong>, un momento hist\u00f3rico en el que las empresas estadounidenses se esfuerzan por alcanzar una nueva era de viajes espaciales comerciales privados.<\/p>\n\n\n\n<p>El primero de los billetes para el viaje del pr\u00f3ximo 20 de julio, ser\u00e1 subastado al p\u00fablico en general.\u00a0<strong>\u201cEstamos ofreciendo un asiento en este primer vuelo al postor ganador de la subasta online de Blue Origin. A partir de hoy, cualquiera puede realizar una oferta de apertura en\u00a0BlueOrigin.com\u201d<\/strong>, comunic\u00f3 la compa\u00f1\u00eda.<\/p>\n\n\n\n<p>La subasta tendr\u00e1 tres fases: del 5 al 9 de mayo el sitio estar\u00e1 abierto a las ofertas; el 19 de mayo esas ofertas ser\u00e1n p\u00fablicas, y los participantes deber\u00e1n superar la oferta m\u00e1s alta para seguir participando; el 12 de junio se celebrar\u00e1 la subasta en vivo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/lacontracara.com\/wp-content\/uploads\/2021\/05\/UMJLUOQD246QPZWYGQE5N5Y4JM.jpg\" alt=\"\" class=\"wp-image-1282\" srcset=\"https:\/\/lacontracara.com\/wp-content\/uploads\/2021\/05\/UMJLUOQD246QPZWYGQE5N5Y4JM.jpg 768w, https:\/\/lacontracara.com\/wp-content\/uploads\/2021\/05\/UMJLUOQD246QPZWYGQE5N5Y4JM-300x200.jpg 300w, https:\/\/lacontracara.com\/wp-content\/uploads\/2021\/05\/UMJLUOQD246QPZWYGQE5N5Y4JM-696x464.jpg 696w, https:\/\/lacontracara.com\/wp-content\/uploads\/2021\/05\/UMJLUOQD246QPZWYGQE5N5Y4JM-630x420.jpg 630w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption>Jeff Bezos, presentando el cohete del m\u00f3dulo de alunizaje de su compa\u00f1\u00eda de exploraci\u00f3n espacial Blue Origin durante un evento en Washington, Estados Unidos. 9 de mayo, 2019. REUTERS\/Clodagh Kilcoyne.<\/figcaption><\/figure>\n\n\n\n<p>\u201c<strong>El monto de la oferta ganadora se donar\u00e1 a la fundaci\u00f3n de Blue Origin, Club for the Future<\/strong>, para inspirar a las generaciones futuras a seguir carreras vinculadas al desarrollo espacial\u201d, inform\u00f3 la empresa de Bezos.<\/p>\n\n\n\n<p>M\u00e1s all\u00e1 de ese primer asiento, se espera que Blue Origin anuncie los detalles sobre c\u00f3mo comprar un asiento, el momento del primer vuelo y el costo de un boleto, que ha sido&nbsp;<strong>un secreto cuidadosamente guardado<\/strong>&nbsp;dentro de Blue durante a\u00f1os. La fecha elegida -20 de julio- no es casual. Se trata del&nbsp;<strong>60 aniversario del viaje de Alan Shepard, el primer estadounidense en el espacio y el segundo humano, detr\u00e1s del ruso Yuri Gagarin, que hab\u00eda viajado tres semanas antes.<\/strong><\/p>\n\n\n\n<p><strong>La combinaci\u00f3n de cohete y c\u00e1psula New Shepard de Blue Origin est\u00e1 dise\u00f1ada para hacer volar de forma aut\u00f3noma a seis pasajeros a m\u00e1s de 100 kil\u00f3metros por encima de la Tierra hacia el espacio suborbital<\/strong>, lo suficientemente alto como para\u00a0<strong>experimentar unos minutos de ingravidez y ver la curvatura del planeta<\/strong>\u00a0antes de que la c\u00e1psula presurizada regrese a la Tierra con paraca\u00eddas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/lacontracara.com\/wp-content\/uploads\/2021\/05\/YDFRBXABSIEIWWLC566FP4CCIA.jpg\" alt=\"\" class=\"wp-image-1281\" srcset=\"https:\/\/lacontracara.com\/wp-content\/uploads\/2021\/05\/YDFRBXABSIEIWWLC566FP4CCIA.jpg 768w, https:\/\/lacontracara.com\/wp-content\/uploads\/2021\/05\/YDFRBXABSIEIWWLC566FP4CCIA-300x200.jpg 300w, https:\/\/lacontracara.com\/wp-content\/uploads\/2021\/05\/YDFRBXABSIEIWWLC566FP4CCIA-696x464.jpg 696w, https:\/\/lacontracara.com\/wp-content\/uploads\/2021\/05\/YDFRBXABSIEIWWLC566FP4CCIA-630x420.jpg 630w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption>El cohete New Shepard (Reuters)<\/figcaption><\/figure>\n\n\n\n<p><strong>La c\u00e1psula cuenta con seis ventanas de observaci\u00f3n que, seg\u00fan Blue Origin, son casi tres veces m\u00e1s altas que las de un avi\u00f3n 747 de Boeing<\/strong>.<\/p>\n\n\n\n<p>Blue Origin anunci\u00f3 la semana pasada que pronto empezar\u00eda a vender billetes, tras a\u00f1os de pruebas y trabajos de desarrollo que han sufrido retrasos.<\/p>\n\n\n\n<p><em>Reuters\u00a0<\/em>inform\u00f3 en 2018 que la empresa estaba planeando cobrar a los pasajeros al menos 200.000 d\u00f3lares por el viaje, bas\u00e1ndose en una evaluaci\u00f3n de los planes rivales de Virgin Galactic del multimillonario Richard Branson y otras consideraciones, aunque su pensamiento puede haber cambiado.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/lacontracara.com\/wp-content\/uploads\/2021\/05\/DC23LYHKVTTWW6W3EIWIOIYCYM.jpg\" alt=\"\" class=\"wp-image-1280\" srcset=\"https:\/\/lacontracara.com\/wp-content\/uploads\/2021\/05\/DC23LYHKVTTWW6W3EIWIOIYCYM.jpg 768w, https:\/\/lacontracara.com\/wp-content\/uploads\/2021\/05\/DC23LYHKVTTWW6W3EIWIOIYCYM-300x200.jpg 300w, https:\/\/lacontracara.com\/wp-content\/uploads\/2021\/05\/DC23LYHKVTTWW6W3EIWIOIYCYM-696x464.jpg 696w, https:\/\/lacontracara.com\/wp-content\/uploads\/2021\/05\/DC23LYHKVTTWW6W3EIWIOIYCYM-630x420.jpg 630w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p>En 2018, un empleado de Blue Origin con conocimiento de primera mano del plan de precios dijo que la compa\u00f1\u00eda comenzar\u00e1 a vender boletos en el&nbsp;<strong>rango de alrededor de USD 200.000 a USD 300.000<\/strong>. Un segundo empleado dijo que los billetes costar\u00edan un m\u00ednimo de 200.000 d\u00f3lares.<\/p>\n\n\n\n<p>Aunque las celebridades y los s\u00faper ricos parecen ser el mercado principal de los viajes de turismo espacial, al menos inicialmente, fuentes de la industria esperan que Blue incluya alg\u00fan componente filantr\u00f3pico en su estrategia de billetes.<\/p>\n\n\n\n<p>Un profesor de ciencias de la universidad y un analista de datos aeroespaciales forman parte de la tripulaci\u00f3n de cuatro miembros que se lanzar\u00e1 a la \u00f3rbita a finales de este a\u00f1o por&nbsp;<strong>SpaceX, de Elon Musk<\/strong>, como parte de&nbsp;<strong>una iniciativa ben\u00e9fica que se anuncia como el primer vuelo espacial totalmente civil de la historia<\/strong>.<\/p>\n\n\n\n<p>Tambi\u00e9n,&nbsp;<strong>Virgin Galactic<\/strong>&nbsp;pretende volar con clientes privados a principios de 2022, tras un primer vuelo con&nbsp;<strong>Branson&nbsp;<\/strong>a bordo a finales de este a\u00f1o. Su experiencia de gravedad cero se basa en su avi\u00f3n SpaceShipTwo, y la empresa tiene planes ambiciosos para ofrecer viajes de punto a punto entre ciudades lejanas a altitudes cercanas al espacio. Virgin dice que cobrar\u00e1 m\u00e1s de 250.000 d\u00f3lares por las nuevas reservas, pero no ha anunciado el precio final. Las ventas se reabrir\u00e1n tras el vuelo de Branson.<\/p>\n\n\n\n<p>El anuncio de Blue Origin proporcionar\u00e1 a Bezos, que fund\u00f3 Amazon,&nbsp;<strong>un impulso muy necesario despu\u00e9s de que Blue Origin perdiera frente a SpaceX un contrato de 2.900 millones de d\u00f3lares en el marco del programa de alto perfil de la NASA<\/strong>&nbsp;para devolver a los estadounidenses a la Luna en los pr\u00f3ximos a\u00f1os.<\/p>\n\n\n\n<p>Sin embargo, la NASA ha pedido a SpaceX que detenga los trabajos de desarrollo relacionados espec\u00edficamente con el contrato del programa lunar a la espera del resultado de las protestas de Blue y de su rival Dynetics ante la Oficina de Responsabilidad del Gobierno de Estados Unidos.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Fuente: Ifobae<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Blue Origin, la empresa de cohetes del multimillonario Jeff Bezos,&nbsp;abrir\u00e1 este mi\u00e9rcoles la venta de billetes para viajes tur\u00edsticos en su nave espacial New Shepard, un momento hist\u00f3rico en el&#8230; <\/p>\n","protected":false},"author":1,"featured_media":1283,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26,22,25],"tags":[],"class_list":["post-1279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales","category-sociedad","category-tecnologia"],"_links":{"self":[{"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/posts\/1279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/comments?post=1279"}],"version-history":[{"count":1,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/posts\/1279\/revisions"}],"predecessor-version":[{"id":1284,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/posts\/1279\/revisions\/1284"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/media\/1283"}],"wp:attachment":[{"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/media?parent=1279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/categories?post=1279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/tags?post=1279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}