{"id":2068,"date":"2021-07-07T17:07:14","date_gmt":"2021-07-07T20:07:14","guid":{"rendered":"https:\/\/lacontracara.com\/?p=2068"},"modified":"2021-07-07T17:07:15","modified_gmt":"2021-07-07T20:07:15","slug":"la-fiscal-poma-pidio-prision-perpetua-para-espinoza-por-el-femicidio-de-una-menor","status":"publish","type":"post","link":"https:\/\/lacontracara.com\/index.php\/2021\/07\/07\/la-fiscal-poma-pidio-prision-perpetua-para-espinoza-por-el-femicidio-de-una-menor\/","title":{"rendered":"La fiscal Poma pidi\u00f3 prisi\u00f3n perpetua para Espinoza por el femicidio de una menor"},"content":{"rendered":"\n<p>Durante la jornada de este mi\u00e9rcoles, en el juicio que se sigue en la Sala II del Tribunal de Juicio contra Walter Alejandro Espinoza como autor de los delitos de homicidio doblemente agravado por ensa\u00f1amiento y por el g\u00e9nero en perjuicio de una menor de 16 a\u00f1os, identificada como Agustina Guedilla, en concurso real con tentativa de homicidio agravado por el g\u00e9nero en perjuicio de una mujer trans, se produjeron los alegatos de las partes.<\/p>\n\n\n\n<p>La fiscala penal de la Unidad de Femicidios, M\u00f3nica Poma, ratific\u00f3 la acusaci\u00f3n contra Espinoza y solicit\u00f3 al Tribunal integrado por los jueces Mar\u00eda Victoria Montoya Quiroga, \u00c1ngel Amadeo Longarte y Carolina Sanguedolce, que se le imponga la pena de prisi\u00f3n perpetua.<\/p>\n\n\n\n<p>El abogado defensor del acusado, en tanto, solicit\u00f3 que sea absuelto en forma lisa y llana y en forma subsidiaria, que sea absuelto por el beneficio de la duda. En caso de ser condenado, solicit\u00f3 que sea sin el agravante de ensa\u00f1amiento.<\/p>\n\n\n\n<p>El Tribunal dispuso un cuarto intermedio hasta las 9 de este jueves 8 de julio para que el acusado tenga la posibilidad de pronunciar sus \u00faltimas palabras y dar a conocer el veredicto.<\/p>\n\n\n\n<p><strong>Fuente: El Tribuno<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante la jornada de este mi\u00e9rcoles, en el juicio que se sigue en la Sala II del Tribunal de Juicio contra Walter Alejandro Espinoza como autor de los delitos de&#8230; <\/p>\n","protected":false},"author":1,"featured_media":2069,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-2068","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiales"],"_links":{"self":[{"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/posts\/2068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/comments?post=2068"}],"version-history":[{"count":1,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/posts\/2068\/revisions"}],"predecessor-version":[{"id":2070,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/posts\/2068\/revisions\/2070"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/media\/2069"}],"wp:attachment":[{"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/media?parent=2068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/categories?post=2068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/tags?post=2068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}