{"id":62175,"date":"2026-01-16T00:57:13","date_gmt":"2026-01-16T03:57:13","guid":{"rendered":"https:\/\/lacontracara.com\/?p=62175"},"modified":"2026-01-16T00:57:13","modified_gmt":"2026-01-16T03:57:13","slug":"provincia-y-camara-de-diputados-trabajan-en-la-actualizacion-del-sistema-de-control-municipal","status":"publish","type":"post","link":"https:\/\/lacontracara.com\/index.php\/2026\/01\/16\/provincia-y-camara-de-diputados-trabajan-en-la-actualizacion-del-sistema-de-control-municipal\/","title":{"rendered":"Provincia y C\u00e1mara de Diputados trabajan en la actualizaci\u00f3n del sistema de control municipal"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La&nbsp;<strong>Sindicatura General de la Provincia (SIGEP)&nbsp;<\/strong>y la C\u00e1mara de Diputados analizaron el modelo de control vigente en la Constituci\u00f3n provincial y su incorporaci\u00f3n en las cartas org\u00e1nicas municipales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con ese objetivo, se realiz\u00f3 un encuentro en el que se revisaron los distintos enfoques adoptados por los municipios y se evaluaron alternativas para promover una adecuada armonizaci\u00f3n normativa que refleje los principios constitucionales y las buenas pr\u00e1cticas de control p\u00fablico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde la C\u00e1mara de Diputados,&nbsp;Ra\u00fal Medina y Guillermo Ramos coincidieron en que este tipo de espacios t\u00e9cnicos favorece un di\u00e1logo constructivo y permite avanzar hacia marcos normativos m\u00e1s s\u00f3lidos y transparentes en toda la provincia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El S\u00edndico General de la Provincia, Federico Mateo, resalt\u00f3 la importancia de esta labor: \u201cDesde la Sindicatura General tenemos un compromiso indelegable con el fortalecimiento de las instituciones. Acompa\u00f1ar a los municipios en este proceso de reforma es invertir en gobernabilidad, transparencia y desarrollo local. Un municipio fuerte, con mecanismos de control s\u00f3lidos, es la base de una provincia m\u00e1s pr\u00f3spera\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, Soledad Sigotto, gerente a cargo de la Coordinaci\u00f3n de la Red de USI y Municipios, destac\u00f3: \u201cEste trabajo no se limita a una mera transferencia de herramientas, sino que es un acompa\u00f1amiento estrat\u00e9gico. Buscamos que los propios municipios, en ejercicio de su autonom\u00eda, se doten de \u00f3rganos de control fuertes y t\u00e9cnicos que prevengan irregularidades, optimicen el uso de los recursos p\u00fablicos y, en definitiva, acerquen una mejor gesti\u00f3n a los vecinos\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La&nbsp;Sindicatura General de la Provincia (SIGEP)&nbsp;y la C\u00e1mara de Diputados analizaron el modelo de control vigente en la Constituci\u00f3n provincial y su incorporaci\u00f3n en las cartas org\u00e1nicas municipales. Con ese&#8230; <\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,18,42,22],"tags":[249,250,35,6817],"class_list":["post-62175","post","type-post","status-publish","format-standard","hentry","category-destacadas","category-politica","category-salta","category-sociedad","tag-argentina","tag-camara-de-diputados","tag-salta","tag-sindicatura-general-de-la-provincia"],"_links":{"self":[{"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/posts\/62175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/comments?post=62175"}],"version-history":[{"count":1,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/posts\/62175\/revisions"}],"predecessor-version":[{"id":62177,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/posts\/62175\/revisions\/62177"}],"wp:attachment":[{"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/media?parent=62175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/categories?post=62175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/tags?post=62175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}