{"id":63346,"date":"2026-01-16T02:30:04","date_gmt":"2026-01-16T05:30:04","guid":{"rendered":"https:\/\/lacontracara.com\/?p=63346"},"modified":"2026-01-16T02:30:04","modified_gmt":"2026-01-16T05:30:04","slug":"tarjeta-estudiantil-provincial-2026-inicia-el-tramite-de-renovacion-para-estudiantes-universitarios-del-interior","status":"publish","type":"post","link":"https:\/\/lacontracara.com\/index.php\/2026\/01\/16\/tarjeta-estudiantil-provincial-2026-inicia-el-tramite-de-renovacion-para-estudiantes-universitarios-del-interior\/","title":{"rendered":"Tarjeta Estudiantil Provincial 2026: inicia el tr\u00e1mite de renovaci\u00f3n para estudiantes universitarios del interior"},"content":{"rendered":"\n<p>La Autoridad Metropolitana de Transporte (AMT) dispuso dar inicio al cronograma para que los estudiantes universitarios puedan renovar el beneficio de la gratuidad mediante la Tarjeta Estudiantil Provincial (TEP), para el ciclo lectivo 2026.<br>&nbsp;<br>Desde el pr\u00f3ximo lunes 12 de enero podr\u00e1n realizar dicho tr\u00e1mite los alumnos del interior del nivel universitario, para acceder al beneficio estudiantil.Como todos los a\u00f1os, para renovar el beneficio deber\u00e1n ingresar a la p\u00e1gina web del organismo www.amtsalta.gob.ar . De esta manera, la AMT realizar\u00e1 la verificaci\u00f3n de la documentaci\u00f3n, dando la aprobaci\u00f3n correspondiente.<br>&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.salta.gob.ar\/public\/images\/noticias\/contenidos\/21429-tarjeta-estudiantil-provincial-2026-inicia-el-tramite-de-renovacion-para-estudiantes-universitarios-del-interior.webp\"><img decoding=\"async\" src=\"https:\/\/www.salta.gob.ar\/public\/images\/noticias\/contenidos\/21429-tarjeta-estudiantil-provincial-2026-inicia-el-tramite-de-renovacion-para-estudiantes-universitarios-del-interior.webp\" alt=\"Tarjeta Estudiantil Provincial 2026: inicia el tr\u00e1mite de renovaci\u00f3n para estudiantes universitarios del interior\" \/><\/a><\/figure>\n\n\n\n<p><strong>Requisitos y recomendaciones para cargar en el sistema de AMT<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Foto de DNI (ambos lados se recomienda aplicaci\u00f3n cam scanner)<\/li>\n\n\n\n<li>Constancia de estudios para el ciclo lectivo 2026<\/li>\n\n\n\n<li>Foto: actualizada del estudiante (Formato tipo carnet en posici\u00f3n erguida, de frente, desde el cuello al extremo superior de la cabeza).<\/li>\n\n\n\n<li>Tramo: prestar atenci\u00f3n a la elecci\u00f3n del tramo y la empresa con la que desea viajar.<\/li>\n\n\n\n<li>Nivel: prestar atenci\u00f3n al nivel educativo que selecciona<\/li>\n<\/ul>\n\n\n\n<p>Para el niveles primario y secundario continua el tr\u00e1mite por primera vez y por renovaci\u00f3n<\/p>\n\n\n\n<p>En el caso que el estudiante deba realizar el tramite por primera vez, deber\u00e1 acercarse a su municipio, para obtener el alta en el sistema.<\/p>\n\n\n\n<p>En cuanto al tr\u00e1mite por renovaci\u00f3n, deber\u00e1n cargar la documentaci\u00f3n actualizada de forma online, en el sitio web de la AMT.<\/p>\n\n\n\n<p>Por consultas o inquietudes se pueden comunicar con el \u00e1rea de Usuarios, v\u00eda WhatsApp al 3874668989.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Autoridad Metropolitana de Transporte (AMT) dispuso dar inicio al cronograma para que los estudiantes universitarios puedan renovar el beneficio de la gratuidad mediante la Tarjeta Estudiantil Provincial (TEP), para&#8230; <\/p>\n","protected":false},"author":6,"featured_media":63347,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[249,1621,1424,79,35,6935],"class_list":["post-63346","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedad","tag-argentina","tag-autoridad-metropolitana-de-transporte","tag-pase-libre","tag-saeta","tag-salta","tag-universitarios"],"_links":{"self":[{"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/posts\/63346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/comments?post=63346"}],"version-history":[{"count":1,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/posts\/63346\/revisions"}],"predecessor-version":[{"id":63348,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/posts\/63346\/revisions\/63348"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/media\/63347"}],"wp:attachment":[{"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/media?parent=63346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/categories?post=63346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/tags?post=63346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}