{"id":65490,"date":"2026-02-11T16:33:16","date_gmt":"2026-02-11T19:33:16","guid":{"rendered":"https:\/\/lacontracara.com\/?p=65490"},"modified":"2026-02-11T16:33:16","modified_gmt":"2026-02-11T19:33:16","slug":"formacion-interdisciplinaria-de-bienestar-policial-a-efectivos-de-cachi","status":"publish","type":"post","link":"https:\/\/lacontracara.com\/index.php\/2026\/02\/11\/formacion-interdisciplinaria-de-bienestar-policial-a-efectivos-de-cachi\/","title":{"rendered":"Formaci\u00f3n interdisciplinaria de Bienestar Policial a efectivos de Cachi"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Se instruy\u00f3 a los efectivos sobre estrategias para una comunicaci\u00f3n asertiva, salud emocional, herramientas de mediaci\u00f3n aplicada en distintos contextos. Participaron polic\u00edas de distintas \u00e1reas y jerarqu\u00edas del Distrito de Prevenci\u00f3n 12.<\/h2>\n\n\n\n<p>La coordinadora de Bienestar Policial,&nbsp;<strong>Nelly Gim\u00e9nez<\/strong>, encabez\u00f3 la apertura de una jornada de formaci\u00f3n interdisciplinaria a efectivos de distintas \u00e1reas y jerarqu\u00edas del Distrito de Prevenci\u00f3n 12 que se desempe\u00f1an en dependencias de Cachi, Payogasta, entre otras de la jurisdicci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.salta.gob.ar\/public\/images\/noticias\/contenidos\/21789-formacion-interdisciplinaria-de-bienestar-policial-a-efectivos-de-cachi.webp\"><img decoding=\"async\" src=\"https:\/\/www.salta.gob.ar\/public\/images\/noticias\/contenidos\/21789-formacion-interdisciplinaria-de-bienestar-policial-a-efectivos-de-cachi.webp\" alt=\"Formaci\u00f3n interdisciplinaria de Bienestar Policial a efectivos de Cachi\" \/><\/a><\/figure>\n\n\n\n<p>En ese marco, profesionales de distintas \u00e1reas brindaron herramientas sobre comunicaci\u00f3n asertiva, salud emocional, prevenci\u00f3n de problem\u00e1ticas sociales, mediaci\u00f3n aplicado en diferentes contextos como ser el \u00e1mbito laboral, social, y personal orientado al bienestar y acompa\u00f1amiento de los miembros de la Fuerza de Seguridad.<\/p>\n\n\n\n<p>Expusieron profesionales de la Direcci\u00f3n de G\u00e9nero de la Polic\u00eda, de la Direcci\u00f3n de Jur\u00eddico, de la Divisi\u00f3n de Bienestar Policial, Divisi\u00f3n Psicosocial, Capellan\u00eda institucional.<\/p>\n\n\n\n<p>Cabe destacar que desde la Coordinaci\u00f3n de Bienestar Policial llevan adelante distintos programas de capacitaci\u00f3n sobre distintos temas a miembros de las Fuerzas de Seguridad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se instruy\u00f3 a los efectivos sobre estrategias para una comunicaci\u00f3n asertiva, salud emocional, herramientas de mediaci\u00f3n aplicada en distintos contextos. Participaron polic\u00edas de distintas \u00e1reas y jerarqu\u00edas del Distrito de&#8230; <\/p>\n","protected":false},"author":6,"featured_media":65491,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,23,42],"tags":[249,7106,1080,5769,471,35],"class_list":["post-65490","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-policiales","category-salta","tag-argentina","tag-bienestar-policial","tag-cachi","tag-nelly-gimenez","tag-policia","tag-salta"],"_links":{"self":[{"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/posts\/65490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/comments?post=65490"}],"version-history":[{"count":1,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/posts\/65490\/revisions"}],"predecessor-version":[{"id":65492,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/posts\/65490\/revisions\/65492"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/media\/65491"}],"wp:attachment":[{"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/media?parent=65490"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/categories?post=65490"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lacontracara.com\/index.php\/wp-json\/wp\/v2\/tags?post=65490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}